{"id":1354,"date":"2017-12-26T11:44:02","date_gmt":"2017-01-26T11:44:02","guid":{"rendered":"http:\/\/devel.turismorural-eltorcal.com\/product\/casa-el-torcal\/"},"modified":"2023-11-27T17:24:26","modified_gmt":"2023-11-27T16:24:26","slug":"casa-el-torcal","status":"publish","type":"product","link":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/","title":{"rendered":"Casa El Torcal"},"content":{"rendered":"<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"text-wrap\">\n<div class=\"wpsbc-container wpsbc-calendar-13\" data-id=\"13\" data-show_title=\"1\" data-months_to_show=\"3\" data-start_weekday=\"1\" data-show_legend=\"1\" data-legend_position=\"side\" data-show_button_navigation=\"1\" data-show_selector_navigation=\"1\" data-show_week_numbers=\"0\" data-current_year=\"2026\" data-current_month=\"5\" data-jump_months=\"0\" data-highlight_today=\"0\" data-history=\"1\" data-show_tooltip=\"1\" data-language=\"fr\" data-min_width=\"200\" data-max_width=\"380\"><h2>Casa El Torcal<\/h2><div class=\"wpsbc-calendars-wrapper wpsbc-legend-position-side\"><div class=\"wpsbc-legend\"><div class=\"wpsbc-legend-item\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><span class=wpsbc-legend-item-name>Available<\/span><\/div><div class=\"wpsbc-legend-item\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-62\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><span class=wpsbc-legend-item-name>Booked<\/span><\/div><\/div><div class=\"wpsbc-calendars\"><div class=\"wpsbc-calendar\"><div class=\"wpsbc-calendar-header wpsbc-heading\"><div class=\"wpsbc-calendar-header-navigation\"><a href=\"#\" class=\"wpsbc-prev\" aria-label=\"Navigate to Previous Month\"><span class=\"wpsbc-arrow\"><\/span><\/a><div class=\"wpsbc-select-container\"><select aria-label=\"Month Selector\"><option value=\"1771113600\">F\u00e9vrier 2026<\/option><option value=\"1773532800\">Mars 2026<\/option><option value=\"1776211200\">Avril 2026<\/option><option value=\"1778803200\"  selected='selected'>Mai 2026<\/option><option value=\"1781481600\">Juin 2026<\/option><option value=\"1784073600\">Juillet 2026<\/option><option value=\"1786752000\">Ao\u00fbt 2026<\/option><option value=\"1789430400\">Septembre 2026<\/option><option value=\"1792022400\">Octobre 2026<\/option><option value=\"1794700800\">Novembre 2026<\/option><option value=\"1797292800\">D\u00e9cembre 2026<\/option><option value=\"1799971200\">Janvier 2027<\/option><option value=\"1802649600\">F\u00e9vrier 2027<\/option><option value=\"1805068800\">Mars 2027<\/option><option value=\"1807747200\">Avril 2027<\/option><option value=\"1810339200\">Mai 2027<\/option><\/select><\/div><\/div><\/div><div class=\"wpsbc-calendar-wrapper\"><table><thead><tr><th>L<\/th><th>M<\/th><th>M<\/th><th>J<\/th><th>V<\/th><th>S<\/th><th>D<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"1\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"2\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"3\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">3<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"4\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"5\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"6\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"7\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"8\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"9\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"10\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">10<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"11\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"12\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"13\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"14\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"15\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"16\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"17\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">17<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"18\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"19\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"20\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"21\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"22\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"23\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"24\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">24<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"25\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"26\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"27\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"28\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"29\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"30\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"5\" data-day=\"31\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">31<\/span><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"wpsbc-calendar\"><div class=\"wpsbc-calendar-header wpsbc-heading\"><div class=\"wpsbc-calendar-header-navigation\">Juin 2026<\/div><\/div><div class=\"wpsbc-calendar-wrapper\"><table><thead><tr><th>L<\/th><th>M<\/th><th>M<\/th><th>J<\/th><th>V<\/th><th>S<\/th><th>D<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"1\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"2\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"3\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"4\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"5\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"6\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"7\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">7<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"8\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"9\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"10\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"11\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"12\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"13\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"14\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">14<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"15\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"16\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"17\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"18\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"19\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"20\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"21\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">21<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"22\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"23\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"24\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"25\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"26\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"27\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"28\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">28<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"29\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"6\" data-day=\"30\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"wpsbc-calendar\"><div class=\"wpsbc-calendar-header wpsbc-heading\"><div class=\"wpsbc-calendar-header-navigation\">Juillet 2026<a href=\"#\" class=\"wpsbc-next\" aria-label=\"Navigate to Next Month\"><span class=\"wpsbc-arrow\"><\/span><\/a><\/div><\/div><div class=\"wpsbc-calendar-wrapper\"><table><thead><tr><th>L<\/th><th>M<\/th><th>M<\/th><th>J<\/th><th>V<\/th><th>S<\/th><th>D<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"1\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"2\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"3\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"4\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"5\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">5<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"6\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"7\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"8\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"9\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"10\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"11\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"12\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">12<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"13\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"14\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"15\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"16\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"17\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"18\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"19\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">19<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"20\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"21\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"22\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"23\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"24\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"25\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"26\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">26<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"27\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"28\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"29\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"30\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date wpsbc-legend-item-61   \" data-year=\"2026\" data-month=\"7\" data-day=\"31\"><div class=\"wpsbc-legend-item-icon wpsbc-legend-item-icon-61\" data-type=\"single\"><div class=\"wpsbc-legend-item-icon-color\"><\/div><div class=\"wpsbc-legend-item-icon-color\"><\/div><\/div><div class=\"wpsbc-date-inner\"><span class=\"wpsbc-date-number\">31<\/span><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><td><div class=\"wpsbc-date   wpsbc-gap \"><div class=\"wpsbc-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><style>.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-61 div:first-of-type { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-61 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-61 div:first-of-type svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-61 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-ical-changeover .wpsbc-legend-item-icon:after {background-color: #ddffcc;}.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-62 div:first-of-type { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-62 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-62 div:first-of-type svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-62 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-63 div:first-of-type { background-color: #fee2a0 !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-63 div:nth-of-type(2) { background-color: transparent !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-63 div:first-of-type svg { fill: #fee2a0 !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-63 div:nth-of-type(2) svg { fill: transparent !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-64 div:first-of-type { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-64 div:nth-of-type(2) { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-64 div:first-of-type svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-64 div:nth-of-type(2) svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-65 div:first-of-type { background-color: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-65 div:nth-of-type(2) { background-color: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-65 div:first-of-type svg { fill: #ffc0bd !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-65 div:nth-of-type(2) svg { fill: #ddffcc !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-date-today .wpsbc-legend-item-icon { border: 4px solid rgba( 33,150,243, .9 ) !important; }.wpsbc-container.wpsbc-calendar-13 .wpsbc-legend-item-icon-0 div:first-of-type { background-color: #e1e1e1 !important; }<\/style><div class=\"wpsbc-container-loaded\" data-just-loaded=\"1\"><\/div><\/div>\n<p>Casa el Torcal est un chalet r\u00e9cemment construit avec jardin et piscine. Situ\u00e9 dans la nature, avec vue sur le parc naturel El Torcal.<br \/>\nLa maison est parfaitement adapt\u00e9 pour une saison calme et de briser la routine quotidienne en compagnie de la famille et les amis.<br \/>\nLa maison a une belle piscine, enti\u00e8rement cl\u00f4tur\u00e9 et entour\u00e9 de fleurs et de plantes qui en font un coin tr\u00e8s agr\u00e9able et appr\u00e9ci\u00e9 par ceux qui visitent.<\/p>\n<p>La maison est situ\u00e9e dans Antequera, La Higuera, au sud du parc naturel Le Torcal.<br \/>\nLa maison Casa el Torcal est situ\u00e9e dans le hameau de La Higuera, dans lequel un petit supermarch\u00e9 et un bar est \u00e0. Il se trouve \u00e0 10 minutes en voiture du La Joya ou Villanueva de la Concepci\u00f3n dans les deux villes peuvent trouver des supermarch\u00e9s, boulangerie, tabac, pharmacie, bars et restaurants.<br \/>\nSa situation au c\u0153ur de l&rsquo;Andalousie et la proximit\u00e9 de l&rsquo;autoroute, il est un endroit id\u00e9al pour visiter d&rsquo;autres villes comme S\u00e9ville, Cordoue et Grenade.<br \/>\nD&rsquo;autres points d&rsquo;int\u00e9r\u00eat sont le Caminito del Rey et El Chorro, le las Parc Naturel de la Sierra de Nieves, Ronda ou Antequera.<\/p>\n<p>Num\u00e9ro d&rsquo;enregistrement: VTAR\/MA\/01055<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt;\"><strong>Caract\u00e9ristiques<\/strong><\/span><\/p>\n<p><strong>Distribution:<\/strong><\/p>\n<ul>\n<li>1 Salle \u00e0 manger\/salon et chemin\u00e9e ouverte et Cuisine<\/li>\n<li>1 Chambres avec lits doubles<\/li>\n<li>2 Chambres avec 2 lits simples<\/li>\n<li>2 Salles de bain (une avec douche, une avec baignoire)<\/li>\n<\/ul>\n<p><strong>\u00c9quipement:<\/strong><\/p>\n<ul>\n<li>Draps, serviettes de bain et serviettes pour la piscine<\/li>\n<li>Lit d&rsquo;enfant<\/li>\n<li>Machine \u00e0 laver la vaisselle<\/li>\n<li>Machine \u00e0 laver<\/li>\n<li>T\u00e9l\u00e9vision: Satellite TV<\/li>\n<li>Equipement de musique<\/li>\n<li>Chauffage radiateurs \u00e9lectriques<\/li>\n<li>Acc\u00e8s gratuit \u00e0 Internet (W-LAN)<\/li>\n<\/ul>\n<p><strong>A l&rsquo;ext\u00e9rieur, jardin et piscine:<\/strong><\/p>\n<ul>\n<li>Barbecue<\/li>\n<li>Parasol<\/li>\n<li>Terrasse \/ Pergola<\/li>\n<li>Bancs et table en bois<\/li>\n<li>Chaises et table de jardin<\/li>\n<li>Construit places assises dans le jardin<\/li>\n<li>6 Chaises longues<\/li>\n<li>Piscine 4 x 8 m, avec \u00e9chelle, entour\u00e9e de pelouse, cl\u00f4tur\u00e9e et ouverte toute l&rsquo;ann\u00e9e.<\/li>\n<\/ul>\n<p>Superficie de la maison 110 m\u00b2<br \/>\nSuperficie de la propri\u00e9t\u00e9 2.500 m\u00b2<\/p>\n<p>D&rsquo;autres d\u00e9tails: La propi\u00e9t\u00e9 est clotur\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt;\"><strong>Animaux<\/strong><\/span><\/p>\n<\/div>\n<p>Animaux permis<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Casa el Torcal est un chalet r\u00e9cemment construit avec jardin et piscine. Situ\u00e9 dans la nature, avec vue sur le parc naturel El Torcal.<\/p>\n","protected":false},"featured_media":1357,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[169],"product_tag":[],"class_list":{"0":"post-1354","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-maisons-rurales","7":"tour_category-3-dormitorios-fr","8":"tour_category-6-personas-fr","9":"tour_category-casas-rurales-fr","10":"tour_category-piscina-fr","11":"tour_category-wifi-fr","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-tour"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa El Torcal - Turismo Rural Sur El Torcal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa El Torcal - Turismo Rural Sur El Torcal\" \/>\n<meta property=\"og:description\" content=\"Casa el Torcal est un chalet r\u00e9cemment construit avec jardin et piscine. Situ\u00e9 dans la nature, avec vue sur le parc naturel El Torcal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo Rural Sur El Torcal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/turismoruraleltorcal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T16:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismorural-eltorcal.com\/wp-content\/uploads\/casa-rural-el-torcal-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RuralTorcal\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/\",\"url\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/\",\"name\":\"Casa El Torcal - Turismo Rural Sur El Torcal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/wp-content\\\/uploads\\\/casa-rural-el-torcal-8.jpg\",\"datePublished\":\"2017-01-26T11:44:02+00:00\",\"dateModified\":\"2023-11-27T16:24:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/wp-content\\\/uploads\\\/casa-rural-el-torcal-8.jpg\",\"contentUrl\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/wp-content\\\/uploads\\\/casa-rural-el-torcal-8.jpg\",\"width\":1900,\"height\":1272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/maisons-rurales\\\/casa-el-torcal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa El Torcal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/\",\"name\":\"Turismo Rural Sur El Torcal\",\"description\":\"Des maisons rurales avec enchantement dans les endroits du Torcal d'Antequera\",\"publisher\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#organization\",\"name\":\"Turismo Rural Sur El Torcal\",\"url\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.turismorural-eltorcal.com\\\/wp-content\\\/uploads\\\/turismo-rural-sur-el-torcal-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.turismorural-eltorcal.com\\\/wp-content\\\/uploads\\\/turismo-rural-sur-el-torcal-logo.png\",\"width\":400,\"height\":50,\"caption\":\"Turismo Rural Sur El Torcal\"},\"image\":{\"@id\":\"https:\\\/\\\/turismorural-eltorcal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/turismoruraleltorcal\\\/\",\"https:\\\/\\\/x.com\\\/RuralTorcal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa El Torcal - Turismo Rural Sur El Torcal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/","og_locale":"fr_FR","og_type":"article","og_title":"Casa El Torcal - Turismo Rural Sur El Torcal","og_description":"Casa el Torcal est un chalet r\u00e9cemment construit avec jardin et piscine. Situ\u00e9 dans la nature, avec vue sur le parc naturel El Torcal.","og_url":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/","og_site_name":"Turismo Rural Sur El Torcal","article_publisher":"https:\/\/www.facebook.com\/turismoruraleltorcal\/","article_modified_time":"2023-11-27T16:24:26+00:00","og_image":[{"width":1900,"height":1272,"url":"https:\/\/turismorural-eltorcal.com\/wp-content\/uploads\/casa-rural-el-torcal-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@RuralTorcal","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/","url":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/","name":"Casa El Torcal - Turismo Rural Sur El Torcal","isPartOf":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/#primaryimage"},"image":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/#primaryimage"},"thumbnailUrl":"https:\/\/turismorural-eltorcal.com\/wp-content\/uploads\/casa-rural-el-torcal-8.jpg","datePublished":"2017-01-26T11:44:02+00:00","dateModified":"2023-11-27T16:24:26+00:00","breadcrumb":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/#primaryimage","url":"https:\/\/turismorural-eltorcal.com\/wp-content\/uploads\/casa-rural-el-torcal-8.jpg","contentUrl":"https:\/\/turismorural-eltorcal.com\/wp-content\/uploads\/casa-rural-el-torcal-8.jpg","width":1900,"height":1272},{"@type":"BreadcrumbList","@id":"https:\/\/turismorural-eltorcal.com\/fr\/maisons-rurales\/casa-el-torcal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turismorural-eltorcal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/turismorural-eltorcal.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Casa El Torcal"}]},{"@type":"WebSite","@id":"https:\/\/turismorural-eltorcal.com\/fr\/#website","url":"https:\/\/turismorural-eltorcal.com\/fr\/","name":"Turismo Rural Sur El Torcal","description":"Des maisons rurales avec enchantement dans les endroits du Torcal d'Antequera","publisher":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismorural-eltorcal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/turismorural-eltorcal.com\/fr\/#organization","name":"Turismo Rural Sur El Torcal","url":"https:\/\/turismorural-eltorcal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/turismorural-eltorcal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.turismorural-eltorcal.com\/wp-content\/uploads\/turismo-rural-sur-el-torcal-logo.png","contentUrl":"https:\/\/www.turismorural-eltorcal.com\/wp-content\/uploads\/turismo-rural-sur-el-torcal-logo.png","width":400,"height":50,"caption":"Turismo Rural Sur El Torcal"},"image":{"@id":"https:\/\/turismorural-eltorcal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/turismoruraleltorcal\/","https:\/\/x.com\/RuralTorcal"]}]}},"_links":{"self":[{"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/product\/1354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/comments?post=1354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/media\/1357"}],"wp:attachment":[{"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/media?parent=1354"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1354"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1354"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/turismorural-eltorcal.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}